{"id":204482,"date":"2025-07-30T09:00:05","date_gmt":"2025-07-30T07:00:05","guid":{"rendered":"https:\/\/www.zoover.nl\/blog\/?p=204482"},"modified":"2025-07-30T08:39:50","modified_gmt":"2025-07-30T06:39:50","slug":"deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan","status":"publish","type":"post","link":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan","title":{"rendered":"Deze 9 bezienswaardigheden in Side mag je niet overslaan"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1869,"featured_media":219945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-204482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bezienswaardigheden"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deze 9 bezienswaardigheden in Side mag je niet overslaan<\/title>\n<meta name=\"description\" content=\"Ga je op vakantie naar Side in de Turkse Rivi\u00e8ra? Zoover tipt de 9 bezienswaardigheden in Side die je echt niet mag missen! \ud83e\udd29\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deze 9 bezienswaardigheden in Side mag je niet overslaan\" \/>\n<meta property=\"og:description\" content=\"Ga je op vakantie naar Side in de Turkse Rivi\u00e8ra? Zoover tipt de 9 bezienswaardigheden in Side die je echt niet mag missen! \ud83e\udd29\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\" \/>\n<meta property=\"og:site_name\" content=\"Zoover vakantieblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Zoover\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T07:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kayleigh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zoover\" \/>\n<meta name=\"twitter:site\" content=\"@zoover\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kayleigh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\"},\"author\":{\"name\":\"Kayleigh\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/#\/schema\/person\/791cb4fb8c355aa74f86c0c3495305e5\"},\"headline\":\"Deze 9 bezienswaardigheden in Side mag je niet overslaan\",\"datePublished\":\"2025-07-30T07:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png\",\"articleSection\":[\"Bezienswaardigheden\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\",\"url\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\",\"name\":\"Deze 9 bezienswaardigheden in Side mag je niet overslaan\",\"isPartOf\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png\",\"datePublished\":\"2025-07-30T07:00:05+00:00\",\"description\":\"Ga je op vakantie naar Side in de Turkse Rivi\u00e8ra? Zoover tipt de 9 bezienswaardigheden in Side die je echt niet mag missen! \ud83e\udd29\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage\",\"url\":\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png\",\"contentUrl\":\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png\",\"width\":1500,\"height\":500,\"caption\":\"Deze 9 bezienswaardigheden in Side mag je niet overslaan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.zoover.nl\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deze 9 bezienswaardigheden in Side mag je niet overslaan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/#website\",\"url\":\"https:\/\/www.zoover.nl\/blog\/\",\"name\":\"Zoover vakantieblog\",\"description\":\"Vakantietips, accommodaties en meer\",\"publisher\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zoover.nl\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/#organization\",\"name\":\"Zoover\",\"url\":\"https:\/\/www.zoover.nl\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2018\/12\/zoover-logo.png\",\"contentUrl\":\"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2018\/12\/zoover-logo.png\",\"width\":790,\"height\":320,\"caption\":\"Zoover\"},\"image\":{\"@id\":\"https:\/\/www.zoover.nl\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Zoover\/\",\"https:\/\/x.com\/zoover\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/#\/schema\/person\/791cb4fb8c355aa74f86c0c3495305e5\",\"name\":\"Kayleigh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.zoover.nl\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62a573d8449e96e6c5da98b38e79ca67?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62a573d8449e96e6c5da98b38e79ca67?s=96&d=mm&r=g\",\"caption\":\"Kayleigh\"},\"url\":\"https:\/\/www.zoover.nl\/blog\/author\/kayleigh\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deze 9 bezienswaardigheden in Side mag je niet overslaan","description":"Ga je op vakantie naar Side in de Turkse Rivi\u00e8ra? Zoover tipt de 9 bezienswaardigheden in Side die je echt niet mag missen! \ud83e\udd29","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan","og_locale":"nl_NL","og_type":"article","og_title":"Deze 9 bezienswaardigheden in Side mag je niet overslaan","og_description":"Ga je op vakantie naar Side in de Turkse Rivi\u00e8ra? Zoover tipt de 9 bezienswaardigheden in Side die je echt niet mag missen! \ud83e\udd29","og_url":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan","og_site_name":"Zoover vakantieblog","article_publisher":"https:\/\/www.facebook.com\/Zoover\/","article_published_time":"2025-07-30T07:00:05+00:00","og_image":[{"width":1500,"height":500,"url":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png","type":"image\/png"}],"author":"Kayleigh","twitter_card":"summary_large_image","twitter_creator":"@zoover","twitter_site":"@zoover","twitter_misc":{"Geschreven door":"Kayleigh","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#article","isPartOf":{"@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan"},"author":{"name":"Kayleigh","@id":"https:\/\/www.zoover.nl\/blog\/#\/schema\/person\/791cb4fb8c355aa74f86c0c3495305e5"},"headline":"Deze 9 bezienswaardigheden in Side mag je niet overslaan","datePublished":"2025-07-30T07:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan"},"wordCount":8,"publisher":{"@id":"https:\/\/www.zoover.nl\/blog\/#organization"},"image":{"@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage"},"thumbnailUrl":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png","articleSection":["Bezienswaardigheden"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan","url":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan","name":"Deze 9 bezienswaardigheden in Side mag je niet overslaan","isPartOf":{"@id":"https:\/\/www.zoover.nl\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage"},"image":{"@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage"},"thumbnailUrl":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png","datePublished":"2025-07-30T07:00:05+00:00","description":"Ga je op vakantie naar Side in de Turkse Rivi\u00e8ra? Zoover tipt de 9 bezienswaardigheden in Side die je echt niet mag missen! \ud83e\udd29","breadcrumb":{"@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#primaryimage","url":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png","contentUrl":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2023\/07\/Deze-9-bezienswaardigheden-in-Side-mag-je-niet-overslaan.png","width":1500,"height":500,"caption":"Deze 9 bezienswaardigheden in Side mag je niet overslaan"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zoover.nl\/blog\/bezienswaardigheden\/deze-9-bezienswaardigheden-in-side-mag-je-niet-overslaan#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zoover.nl\/blog\/"},{"@type":"ListItem","position":2,"name":"Deze 9 bezienswaardigheden in Side mag je niet overslaan"}]},{"@type":"WebSite","@id":"https:\/\/www.zoover.nl\/blog\/#website","url":"https:\/\/www.zoover.nl\/blog\/","name":"Zoover vakantieblog","description":"Vakantietips, accommodaties en meer","publisher":{"@id":"https:\/\/www.zoover.nl\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zoover.nl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.zoover.nl\/blog\/#organization","name":"Zoover","url":"https:\/\/www.zoover.nl\/blog\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.zoover.nl\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2018\/12\/zoover-logo.png","contentUrl":"https:\/\/www.zoover.nl\/blog\/wp-content\/uploads\/2018\/12\/zoover-logo.png","width":790,"height":320,"caption":"Zoover"},"image":{"@id":"https:\/\/www.zoover.nl\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Zoover\/","https:\/\/x.com\/zoover"]},{"@type":"Person","@id":"https:\/\/www.zoover.nl\/blog\/#\/schema\/person\/791cb4fb8c355aa74f86c0c3495305e5","name":"Kayleigh","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.zoover.nl\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62a573d8449e96e6c5da98b38e79ca67?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62a573d8449e96e6c5da98b38e79ca67?s=96&d=mm&r=g","caption":"Kayleigh"},"url":"https:\/\/www.zoover.nl\/blog\/author\/kayleigh"}]}},"_links":{"self":[{"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/posts\/204482"}],"collection":[{"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/users\/1869"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/comments?post=204482"}],"version-history":[{"count":2,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/posts\/204482\/revisions"}],"predecessor-version":[{"id":219944,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/posts\/204482\/revisions\/219944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/media\/219945"}],"wp:attachment":[{"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/media?parent=204482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/categories?post=204482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zoover.nl\/blog\/wp-json\/wp\/v2\/tags?post=204482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}